{"id":129,"date":"2020-08-06T09:36:14","date_gmt":"2020-08-06T12:36:14","guid":{"rendered":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/?p=129"},"modified":"2020-08-24T12:33:55","modified_gmt":"2020-08-24T15:33:55","slug":"outro-mussum-ipsum","status":"publish","type":"post","link":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/thassio-rodriguez-capranera\/outro-mussum-ipsum\/","title":{"rendered":"A casa das rom\u00e3s: Cap\u00edtulo 1 &#8211; Homo proponit, sed Deus disponit"},"content":{"rendered":"\n<p><em>A S\u00e3o Paulo da d\u00e9cada de trinta era um lugar formid\u00e1vel para os esp\u00edritos que estivessem em busca de divers\u00f5es e entretenimento. <strong>Th\u00e1ssio Rodriguez Capranera<\/strong>, autor de O robe amarelo e Ditirambos na Cant\u00e1bria antiga, nos leva para um tour nesta cidade velha, decadente, chuvosa e secreta. Em <strong>A casa das rom\u00e3s<\/strong>, dois amigos, \u00e9brios e entediados, descobrem nos encantos dos lugares iluminados horrores muito al\u00e9m dos sugeridos na pr\u00f3pria escurid\u00e3o.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><span style=\"text-decoration: underline\">E<\/span>st\u00e1vamos eu e meu amigo Josefo, sentados \u00e0 mesa de um caf\u00e9 na Rua Direita, quando um estranho nos abordou pedindo por f\u00f3sforos. Camilo, impaciente, afugentou-o com um gesto rude e um rosnado; o pobre sujeito, andrajoso, a pele tomada por chagas abertas e vermelhas, \u00famidas, afastou-se, um cachimbo indecentemente escurecido na boca; com o olhar tristonho, aquele prometheus das mazelas foi buscar seu fogo do conhecimento em uma outra mesa.<\/p>\n\n\n\n<p>\u2014 Esses infelizes, n\u00e3o cansam de nos pedir coisas? \u2014 Josefo era um bruto, mas n\u00e3o uma alma ruim, isto deve ser dito.<\/p>\n\n\n\n<p>\u2014 Ora, \u00e9 apenas um pedinte, eles s\u00e3o assim\u2026 N\u00e3o seja t\u00e3o grosseiro.<\/p>\n\n\n\n<p>Josefo levou a x\u00edcara de caf\u00e9 \u00e0 boca, e em um sinal de repulsa ao gosto da bebida, torceu as fei\u00e7\u00f5es e devolveu a x\u00edcara ao seu pires. Uma borboleta amarela pousou sobre a mesa, pr\u00f3ximo de minha bebida. Distra\u00eddo, eu a encarei com aquele assombro que nos toma de assalto quando diante de uma distinta apari\u00e7\u00e3o, enquanto Josefo, irritado, balbuciava e rosnava como um macaco japon\u00eas alguma impreca\u00e7\u00e3o contra o sabor da bebida que lhe fora servida.<\/p>\n\n\n\n<p>N\u00e3o que n\u00e3o gostasse de caf\u00e9, mas Josefo \u2014 e entendam de uma vez por todas \u2014 \u00e9 um desses estetas que encontram defeitos em qualquer coisa na qual possam aplicar seus conhecimentos. Naturalmente, os sabores lhe vinham \u00e0 boca sempre com uma carga insuport\u00e1vel de palestras, as quais proferia, com algum fervor, sempre que algum pobre&nbsp; \u2014 naquela ocasi\u00e3o, eu mesmo \u2014 se fazia presente para ouvi-lo.&nbsp;<\/p>\n\n\n\n<p>\u2014 \u00c1cido demais. N\u00e3o torraram bem o caf\u00e9, deve estar ainda verde. Que desgra\u00e7a para um gr\u00e3o t\u00e3o rico, \u00e9 um puro marroquino!&nbsp;<\/p>\n\n\n\n<p>Espantei a borboleta das asas amarelas sulcadas por rajadas pretas e voltei meu olhar para Josefo. Este me encarava com uma tor\u00e7\u00e3o de ondas violentas estampada no rosto, como se fosse culpa minha a m\u00e1 qualidade de seu caf\u00e9. Pouco me importando com suas reivindica\u00e7\u00f5es mequetrefes, apanhei meu len\u00e7o de bolso e, enxugando as gotas de suor em minha testa cada vez maior, disse-lhe:<\/p>\n\n\n\n<p>\u2014 Vamos pagar a conta e seguir para a livraria, sim? Talvez l\u00e1 encontres algo melhor que caf\u00e9 \u00e1cido mal torrado.<\/p>\n\n\n\n<p>Josefo amoleceu num instante sua m\u00e1scara ex\u00f3tica de guerra e desfez-se em um sorriso de canto de boca, cinza de cigarro.<\/p>\n\n\n\n<p>\u2014 A acidez da literatura me \u00e9 mais detest\u00e1vel que a do caf\u00e9. N\u00e3o suporto seu gosto, Torquato, \u00e9 pior que as leituras dos tempos do Largo. Montesquieu tornou-se meu pior inimigo, e aqueles textos ingleses\u2026 c\u00e9us!<\/p>\n\n\n\n<p>\u2014 N\u00e3o se preocupe, \u2014 Disse a ele, erguendo-me da cadeira \u2014 a livraria que iremos visitar, al\u00e9m de n\u00e3o ficar muito longe deste caf\u00e9, pode ser tomada como uma daquelas formid\u00e1veis cabanas tuaregues onde sempre um insigne patrono de caravana lhe recebe com hospitalidade. N\u00e3o \u00e9 como um lugar desses aqui, onde torram mal seu caf\u00e9. \u2014 E rindo lhe dei um tapa nas costas; est\u00e1vamos j\u00e1 \u00e0 beira do balc\u00e3o \u2014 O dono \u00e9 um desses velhacos que mais se parecem com um Jedidiah do que com um Dickens. Seu gosto por leitura \u00e9 ap\u00f3crifo, nada de chatices vetustas e voluta\u00e7\u00f5es parab\u00f3lico-sint\u00e1ticas.&nbsp;<\/p>\n\n\n\n<p>Josefo me olhou com frieza, e isto significava que havia aceito meu convite; era seu modo de dissimular a confian\u00e7a absoluta que tinha em minhas aventuras. Como havia dito, n\u00e3o era um mau homem, talvez est\u00fapido o suficiente para crer-se inteligente demais, ou requintado demais\u2026 tinha ares de d\u00e2ndi, mas da b\u00edblia dos malditos conhecia somente o salmo 23. Era como um desses crist\u00e3os de porcelana, homens de barro frio que prestam homenagem ao santo sem olhar-lhe o rosto esculpido, n\u00e3o sabem o que est\u00e3o fazendo, e pedem ninharias, exigem mesquinhezas com saibo de farinha de trigo no vapor, e cr\u00eaem que a massa insossa de gr\u00e3os mo\u00eddas lhes ir\u00e1 nutrir o esp\u00edrito como se fosse rara vianda.&nbsp;<\/p>\n\n\n\n<p>Caso tempo tivesse de percorrer com minha tinteiro essas p\u00e1ginas de papel barato que comprei em um velho armaz\u00e9m na Penha, talvez expusesse de Josefo as cadeladas sarabandinas em que se metera por conta desse n\u00e9scio tra\u00e7o de car\u00e1ter, mas permito-me reservar alguns desses casos para outra oportunidade.<\/p>\n\n\n\n<p>Por hora, basta saber que pagamos a magra conta e seguimos, de bra\u00e7os dados e em sil\u00eancio, para o <em>Nephelibatorivm.<\/em>&nbsp;<\/p>\n\n\n\n<p><strong>* * *<\/strong><\/p>\n\n\n\n<p>Quando a esquina da Rua \u00c1lvares Penteado dobramos, para acessar a Rua do Tesouro, ao longe avistei fechada a t\u00edmida porta da pequena livraria, onde podia-se ler, com alguma dificuldade, pintado \u00e0 tinta de branco chumbo sobre uma placa de ip\u00ea inchada de umidade o nome <em>Nephelibatorivm.<\/em> Apontei com o dedo para que meu amigo pudesse ao menos de longe ver o estabelecimento, j\u00e1 que n\u00e3o fazia sentido gastarmos sola at\u00e9 l\u00e1 sendo que estava fechado. Com algum desd\u00e9m, Josefo respondeu-me o gesto:<\/p>\n\n\n\n<p>\u2014 Com um nome desses, talvez tenha falido. \u2014 E deu meia volta, desvencilhando-se de meu bra\u00e7o.<\/p>\n\n\n\n<p>Saibam tamb\u00e9m que Josefo detesta o Latim e toda sua numerosa prole. Meu colega era um germanista, da cepa que teria num camafeu o retrato de Wagner ao lado de Hoffmann, mas nunca um franc\u00eas ou um espanhol. Nisto gra\u00e7a eu achava e muita, pois tinha em conta que talvez fosse meu colega o \u00fanico advogado que havia fugido da total dem\u00eancia latinista da qual sofrem todos os homens das leis, com suas colunas acaneladas e suas estantes repletas de livros encadernados em couro tingido de vermelho turco, e cujos frontisp\u00edcios tentam, com insucesso c\u00f4mico, imitar os frontisp\u00edcios do s\u00e9culo dezoito.&nbsp;<\/p>\n\n\n\n<p>Nunca compreendi essa admira\u00e7\u00e3o descomedida pela est\u00e9tica dos filhos do L\u00e1cio, mas a julgar pelo n\u00famero enfastiante de leituras do g\u00eanero que tem um estudante de direito sobre as esp\u00e1duas, bem\u2026 talvez esteja a\u00ed a resposta para a antipatia de meu amigo para com C\u00edcero e os Graco.&nbsp;<\/p>\n\n\n\n<p>Percebendo que n\u00e3o havia jeito para convencer Josefo a acompanhar-me para qualquer outra batida que fosse, decidi convid\u00e1-lo para uma bebida em meu apartamento, na Riachuelo, onde havia me instalado temporariamente para renovar os ares e, quem sabe, terminar a obra em que estivera trabalhando h\u00e1 algum tempo.&nbsp;<\/p>\n\n\n\n<p>Josefo aceitou, isto enquanto caminh\u00e1vamos rumo \u00e0 sua casa, no final da Rodrigo Silva, pr\u00f3ximo de meu lugar, mas havia uma condi\u00e7\u00e3o para que ele ficasse por mais algumas horas em minha companhia: teria que lhe preparar umas doses da bebida que tanto amava, uma mistura hedionda de Roman\u00e9e Conti, cravo e licor de anis.&nbsp;<\/p>\n\n\n\n<p>Outro gosto que nunca compreendi, e que talvez fosse de sua altura de d\u00e2ndi <em>poseur <\/em>uma falha marca registrada que, mesmo crendo ele tratar-se de um bras\u00e3o de requinte, n\u00e3o passava, \u2014 e isso \u00e9 fato, pois provei dessa diarr\u00e9ia de c\u00f3lera, \u2014 de uma descabida tentativa de notoriedade.&nbsp;<\/p>\n\n\n\n<p>\u00c9 preciso que diga que os bares, isto \u00e9, quando tinham de fato Roman\u00e9e Conti em suas adegas, recusavam-se educadamente a poluir o vinho expendioso com licor barato e arom\u00e1ticos fortes.&nbsp;<\/p>\n\n\n\n<p>Pobre Josefo, o d\u00e2ndi mais est\u00fapido de toda S\u00e3o Paulo!<\/p>\n\n\n\n<p><strong>* * *<\/strong><\/p>\n\n\n\n<p>J\u00e1 em minha casa, grudamos junto ao bar:<\/p>\n\n\n\n<p><strong>\u2014 <\/strong>E como vai seu trabalho? Avan\u00e7as em algo? Da \u00faltima vez que conversamos sobre, estavas empacado como mula na serrania ainda no segundo ato&#8230;<\/p>\n\n\n\n<p>A pergunta de Josefo referia-se \u00e0 obra em que, \u00e0 \u00e9poca, eu trabalhava exaustivamente, por vezes sem chegar a lugar algum. Trata-se de uma trag\u00e9dia em cinco atos, e quem a 14 de outubro de 1922 saiu para divertir-se por algumas horas no Teatro S\u00e3o Pedro, sabe que estou falando de \u201cO mart\u00edrio de S\u00e3o Cipriano\u201d.<\/p>\n\n\n\n<p>\u2014 N\u00e3o vai nada bem, isto \u00e9 fato\u2026 estou mesmo empacado na cena quarta do segundo ato h\u00e1 semanas! \u2014 Isto tudo eu dizia enquanto ao bar preparava a hedionda bebida para meu amigo \u2014 Estou num impasse, destes grotescos, entende? Gostaria de acrescentar \u00e0 arquitetura da obra certas colunas filos\u00f3ficas, em parelha, \u00e9 claro, com os rompantes de paganismo e diabolismo que tanto me agradam, e as poucas cenas c\u00f4micas que sucintamente se desenrolam em uma ou outra cena\u2026 Mas creio que recheei demais a pe\u00e7a com esp\u00edritos salamandrinos e apari\u00e7\u00f5es oraculares\u2026 Sabes, n\u00e3o sou amante da filosofia, e me debru\u00e7ar sobre qualquer tomo de Emp\u00e9docles ou Anaximandro, logo agora\u2026 ah! me custaria um diabo de tempo, e os santos, andam todos surdos! Creio que mudaram-se todos para o Rio.<\/p>\n\n\n\n<p>Meu amigo franziu o cenho, desviou seu olhar para a bebida que eu preparava e, ap\u00f3s lamber os bei\u00e7os, disse a meia-voz:<\/p>\n\n\n\n<p>\u2014 Sei do que precisas, mas tu n\u00e3o aceitarias o convite meu.&nbsp;<\/p>\n\n\n\n<p>\u2014 E como tens tanta certeza disso? \u2014 perguntei-lhe, um tanto indignado.<\/p>\n\n\n\n<p>\u2014 \u00c9 que est\u00e1s sempre metido com estes homens cabe\u00e7udos dos livros, esses esp\u00edritos mofados e enfadonhos que morreram h\u00e1 cent\u00farias\u2026 preferes a velhice caduca que a juventude vigorosa\u2026 \u00e9s um Di\u00f3genes. Digo, n\u00e3o tens luxo, nem prazeres\u2026 ora, e vais dizer que estou mentindo? At\u00e9 os charutos que fumas tem cheiro insosso!&nbsp;<\/p>\n\n\n\n<p>Pronta a bebida, entreguei-lhe o copo e encarei-o com alguma curiosidade em meus olhos. Josefo bebeu do copo com a voracidade de um minerador sedento. Ele depositou o copo em cima do balc\u00e3o, estalou a l\u00edngua, e olhou-me de soslaio. Esperei em sil\u00eancio por uma manifesta\u00e7\u00e3o que n\u00e3o veio, ent\u00e3o senti-me na obriga\u00e7\u00e3o de provoc\u00e1-lo.<\/p>\n\n\n\n<p>\u2014 E j\u00e1 que tens toda a desenvoltura de algu\u00e9m que sabe como de fato divertir-se, o que acha que eu deveria fazer? Beber como um desgarrado como tu?<\/p>\n\n\n\n<p>Josefo apertou os olhos, lambeu novamente os bei\u00e7os e soltou uma risada breve, quase afogada.&nbsp;<\/p>\n\n\n\n<p>\u2014 Te levo para um lugar, e se aceitares\u2026 bem\u2026 prometo-te que ter\u00e1s, pelo menos, algum descanso desses escritores teus que tanto perturbam a tua mente. E quem sabe n\u00e3o consegues encontrar caminho para tua pe\u00e7a?&nbsp;<\/p>\n\n\n\n<p>Josefo n\u00e3o era homem convincente. Eu conhecia seus costumes e suas torpes incurs\u00f5es aos seus mundos de sombra nos mist\u00e9rios da S\u00e3o Paulo. Talvez fosse o t\u00e9dio, ou talvez a vontade agrilhoante de v\u00ea-lo tentar seduzir-me com seus encantos p\u00fatridos de louco charlat\u00e3o; mas aceitei seu convite, e em alguns poucos minutos, est\u00e1vamos os dois dentro de um auto, bebendo licor em um cantil de prata e rumando para a Marechal Deodoro.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u2619\u269c\u2767<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A S\u00e3o Paulo da d\u00e9cada de trinta era um lugar formid\u00e1vel para os esp\u00edritos que estivessem em busca de divers\u00f5es e entretenimento. Th\u00e1ssio Rodriguez Capranera, autor de O robe amarelo e Ditirambos na Cant\u00e1bria antiga, nos leva para um tour nesta cidade velha, decadente, chuvosa e secreta. Em A casa das rom\u00e3s, dois amigos, \u00e9brios &#8230; <a title=\"A casa das rom\u00e3s: Cap\u00edtulo 1 &#8211; Homo proponit, sed Deus disponit\" class=\"read-more\" href=\"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/thassio-rodriguez-capranera\/outro-mussum-ipsum\/\" aria-label=\"Read more about A casa das rom\u00e3s: Cap\u00edtulo 1 &#8211; Homo proponit, sed Deus disponit\">Ler mais<\/a><\/p>\n","protected":false},"author":14,"featured_media":477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[14],"class_list":["post-129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thassio-rodriguez-capranera","tag-terror-sao-paulo"],"_links":{"self":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":2,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"predecessor-version":[{"id":605,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts\/129\/revisions\/605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/media\/477"}],"wp:attachment":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}