{"id":142,"date":"2020-08-11T09:50:40","date_gmt":"2020-08-11T12:50:40","guid":{"rendered":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/?p=142"},"modified":"2020-08-24T12:29:48","modified_gmt":"2020-08-24T15:29:48","slug":"cacilds-vidis","status":"publish","type":"post","link":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/moacir-novaes\/cacilds-vidis\/","title":{"rendered":"Antologia 1: B\u00fafalo"},"content":{"rendered":"\n<p><em>\u00a0Um dos maiores escritores da era dos blogs de fic\u00e7\u00e3o, <strong>Moacir Novaes<\/strong> marca seu retorno com <strong>B\u00fafalo<\/strong>, uma colet\u00e2nea de contos que evocam o candombl\u00e9 e a cultura perif\u00e9rica.<\/em><\/p>\n\n\n\n<p><em>Hist\u00f3rias fant\u00e1sticas e assustadoras, apagadas e silenciadas est\u00e3o escondidas em nosso cotidiano. Elas existem, invis\u00edveis, em meio ao ru\u00eddo constante da cidade de S\u00e3o Paulo.<\/em><\/p>\n\n\n\n<p><em>Na hist\u00f3ria que d\u00e1 nome \u00e0 colet\u00e2nea, numa noite de raios e trov\u00f5es em S\u00e3o Paulo, voc\u00ea poderia sentir a eletricidade no ar\u2026 assim como o gosto ferroso de sangue. Em <strong>O m\u00e9dico preto<\/strong>, em meio ao caos de uma pandemia, um m\u00e9dico demonstra que para a vida prosseguir deve haver morte. <strong>A foto<\/strong> \u00e9 a hist\u00f3ria de um fot\u00f3grafo que usa suas lentes para captar os \u00faltimos instantes de terror de suas v\u00edtimas. Em <strong>O caminho<\/strong>, o autor se vale da fic\u00e7\u00e3o para propor uma quest\u00e3o. E se as escolhas, o livre arb\u00edtrio e as decis\u00f5es que tomamos forem apenas uma ilus\u00e3o? <strong>O vigia<\/strong> nos revela que a pessoa nasce para o que ela \u00e9, e como certos h\u00e1bitos s\u00e3o duros de abandonar&#8230;Mesmo depois da morte. E na \u00faltima hist\u00f3ria, <strong>O machado e a tartaruga<\/strong>, uma exposi\u00e7\u00e3o de arte africana demonstra como a religi\u00e3o do outro \u00e9 sempre um \u201cmito\u201d.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>B\u00fafalo<\/p>\n\n\n\n<p>Ela parecia t\u00e3o s\u00f3bria&#8230; Talvez fosse apenas uma impress\u00e3o superficial.<\/p>\n\n\n\n<p>Parada em um dos cantos do sal\u00e3o, n\u00e3o estava sorrindo ou dan\u00e7ando.<\/p>\n\n\n\n<p>As pulsa\u00e7\u00f5es da m\u00fasica infiltravam-se em cada m\u00ednima fra\u00e7\u00e3o daquele espa\u00e7o.<\/p>\n\n\n\n<p>Menos nela.<\/p>\n\n\n\n<p>Nunca nela.<\/p>\n\n\n\n<p>Era como se houvesse ali um v\u00e1cuo. Ela parecia t\u00e3o s\u00f3bria.<\/p>\n\n\n\n<p>N\u00e3o tinha os olhos confusos ou desesperados.<\/p>\n\n\n\n<p>N\u00e3o estava ansiosa para esquecer algo.<\/p>\n\n\n\n<p>Ao contr\u00e1rio, parecia saber que quem busca vingan\u00e7a nunca pode esquecer.<\/p>\n\n\n\n<p>Jamais deve perdoar ou fechar suas feridas.<\/p>\n\n\n\n<p>Olhe e fique atento, tente ver, e vai notar que \u00e9 como estar diante de um buraco negro.<\/p>\n\n\n\n<p>Silencioso.<\/p>\n\n\n\n<p>Impass\u00edvel.<\/p>\n\n\n\n<p>Ela estava parada, feito um fato inevit\u00e1vel.<\/p>\n\n\n\n<p>Vestida de vermelho.<\/p>\n\n\n\n<p>Cabelos de um tom ainda mais escuro que as roupas. Curtos. Uma figura esguia.<\/p>\n\n\n\n<p>O inexplic\u00e1vel, em sua imagem, tornava-a imediatamente uma mulher bonita para qualquer olhar. Preste aten\u00e7\u00e3o no que digo, ela n\u00e3o era apenas bonita. Era uma mulher.<\/p>\n\n\n\n<p>E existe uma for\u00e7a monstruosa nesse aspecto de sua personalidade.<\/p>\n\n\n\n<p>N\u00e3o uma mo\u00e7a inexperiente ou uma menina que precise de elogios.<\/p>\n\n\n\n<p>Ela era uma mulher e isso fazia toda a diferen\u00e7a.<\/p>\n\n\n\n<p>Sabia ser desejada, instantaneamente, como o dem\u00f4nio sabe ser rejeitado.<\/p>\n\n\n\n<p>Estava entre dois espelhos, por isso voc\u00ea conseguiria ver a tatuagem em suas costas nuas, uma cabe\u00e7a de um b\u00fafalo negro de longos chifres e olhos vazios.<\/p>\n\n\n\n<p>Os tra\u00e7os do desenho eram absolutamente brutais, como cicatrizes, e ainda assim, lindos.<\/p>\n\n\n\n<p>Ela mal percebia a m\u00fasica, dentro da sua cabe\u00e7a havia espa\u00e7o somente para as batidas dos tambores, enlouquecedoras, eternas. Elas eram o seu rosnado, ecoando em cada gesto e pensamento.<\/p>\n\n\n\n<p>Moldando a vontade dela de gritar e destruir tudo ao ser redor.<\/p>\n\n\n\n<p>Obrigando aquela mulher a conter-se. Negar-se.<\/p>\n\n\n\n<p>Durante a \u00faltima hora tr\u00eas homens e duas mulheres tentaram abord\u00e1-la e, em cada uma das tentativas, ocorria o mesmo processo, ela n\u00e3o sorria, olhava diretamente para a outra pessoa, como se desmontasse sua alma. O ato durava alguns segundos.<\/p>\n\n\n\n<p>Depois parecia perder o interesse e simplesmente balan\u00e7ava a cabe\u00e7a.<\/p>\n\n\n\n<p>Negando-se.<\/p>\n\n\n\n<p>Na sexta vez, um homem de cabelos claros se aproximou dela.<\/p>\n\n\n\n<p>Ela o olhou, passando as camadas da alma at\u00e9 chegar ao centro.<\/p>\n\n\n\n<p>Detestava homens violentos.<\/p>\n\n\n\n<p>Odiava ainda mais quando percebia que um deles desculpava-se por todos os erros que tinha cometido em sua imprest\u00e1vel vida.<\/p>\n\n\n\n<p>Os tambores estavam t\u00e3o altos na cabe\u00e7a dela.<\/p>\n\n\n\n<p>Misturavam-se com a voz daquele polaco sorrindo e com a voz dos mortos. As batidas exigiam retribui\u00e7\u00e3o. N\u00e3o apenas dor, mas puni\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cMeu nome \u00e9 Ians\u00e3\u201d<\/p>\n\n\n\n<p>Essa foi a primeira vez que ela sorriu, em seguida, puxou o rapaz pela m\u00e3o para beij\u00e1-lo. A boca dela tinha um gosto de canela ardida. Ela segurou um dos pulsos dele.<\/p>\n\n\n\n<p>Ele a seguiu, sem questionar.<\/p>\n\n\n\n<p>Juntos subiram pelas escadas de inc\u00eandio at\u00e9 o topo do pr\u00e9dio que hospedava o clube.<\/p>\n\n\n\n<p>O c\u00e9u estava escuro.<\/p>\n\n\n\n<p>&nbsp;Nuvens pesadas combinadas com as luzes da cidade. Voc\u00ea n\u00e3o veria os raios, mas, sentiria o cheiro da chuva e os trov\u00f5es.<\/p>\n\n\n\n<p>\u201cVamos fazer aqui?\u201d<\/p>\n\n\n\n<p>\u201cSim. Vamos sim querido.\u201d<\/p>\n\n\n\n<p>Ela se aproximou e segurou seu corpo. Depois o beijou e foi movendo as m\u00e3os at\u00e9 estar tran\u00e7ada a ele.<\/p>\n\n\n\n<p>O prazer inicial rapidamente desapareceu quando o rapaz sentiu os ossos do seu bra\u00e7o e pulsos sendo pressionados at\u00e9 o ponto de trincarem sob a carne.<\/p>\n\n\n\n<p>N\u00e3o havia como afastar a boca do beijo dela, os l\u00e1bios pareciam uma mistura de ferro e sangue seco. N\u00e3o havia como gritar.<\/p>\n\n\n\n<p>O gemido sufocado e repleto de dor s\u00fabita era incrivelmente doce para o paladar dela.<\/p>\n\n\n\n<p>Os olhos escancarados, o medo por estar indefeso.<\/p>\n\n\n\n<p>Tudo era doce e justo.<\/p>\n\n\n\n<p>Sem aviso um raio atingiu o corpo daquela mo\u00e7a, transpassando-a, serpenteando entre os dois amantes. O trov\u00e3o veio logo depois, como resultado do ar superaquecido, mas o som era pequeno, ao menos, se comparado com os tambores.<\/p>\n\n\n\n<p>A corrente el\u00e9trica ainda estalava no ar quando o homem caiu fulminado no ch\u00e3o.<\/p>\n\n\n\n<p>A mulher olhou para o corpo dele, para as queimaduras e ferimentos.<\/p>\n\n\n\n<p>Ele ainda respirava.<\/p>\n\n\n\n<p>Devagar e aflito.<\/p>\n\n\n\n<p>Ela abaixou-se e colocou uma das m\u00e3os sobre o peito dele.<\/p>\n\n\n\n<p>Encarava-o, esperando o cora\u00e7\u00e3o parar de bater, inconscientemente, comparava aquelas batidas aos tambores na sua cabe\u00e7a.<\/p>\n\n\n\n<p>Queria guardar o momento.<\/p>\n\n\n\n<p>Tum&#8230;. Tum&#8230; Tum&#8230; &#8230;. Tum&#8230; &#8230; &#8230; &#8230; e depois o nada.<\/p>\n\n\n\n<p>Os tambores ainda estavam l\u00e1, dentro da cabe\u00e7a dela, entre seus pensamos.<\/p>\n\n\n\n<p>J\u00e1 o cora\u00e7\u00e3o dele n\u00e3o estava mais.<\/p>\n\n\n\n<p>Ela se levantou, refez o caminho para dentro do pr\u00e9dio.<\/p>\n\n\n\n<p>Os trov\u00f5es faziam o ar em toda cidade vibrar, vidros tremiam e concreto reverberava com os estrondos.<\/p>\n\n\n\n<p>Ainda assim, eram sons pequenos.<\/p>\n\n\n\n<p>Ao menos se comparados aos tambores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Um dos maiores escritores da era dos blogs de fic\u00e7\u00e3o, Moacir Novaes marca seu retorno com B\u00fafalo, uma colet\u00e2nea de contos que evocam o candombl\u00e9 e a cultura perif\u00e9rica. Hist\u00f3rias fant\u00e1sticas e assustadoras, apagadas e silenciadas est\u00e3o escondidas em nosso cotidiano. Elas existem, invis\u00edveis, em meio ao ru\u00eddo constante da cidade de S\u00e3o Paulo. Na &#8230; <a title=\"Antologia 1: B\u00fafalo\" class=\"read-more\" href=\"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/moacir-novaes\/cacilds-vidis\/\" aria-label=\"Read more about Antologia 1: B\u00fafalo\">Ler mais<\/a><\/p>\n","protected":false},"author":14,"featured_media":476,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[14],"class_list":["post-142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moacir-novaes","tag-terror-sao-paulo"],"_links":{"self":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":2,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts\/142\/revisions"}],"predecessor-version":[{"id":612,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/posts\/142\/revisions\/612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/media\/476"}],"wp:attachment":[{"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/media?parent=142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/categories?post=142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portfolio.sitedeartista.com.br\/sobreasombra\/wp-json\/wp\/v2\/tags?post=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}